{"id":65,"count":11,"description":"For over fifty years, the infrastructure sector has been one of Vittadello Group\u2019s core businesses. The Group boasts a long series of works on communication routes, highways and railways. Throughout Italy Vittadello has put at the service of the client engineering skills and cutting-edge construction techniques for the construction of highways, junctions, tunnels, viaducts and other road works that has supervised all phases of construction. Efficiency, flexibility, collaboration and transparency were key factors in the success of the company. Vittadello Group holds SOA certification in general and specialized categories, with an \"unlimited\" classification, for most public works sectors and applies an Integrated Management System (Quality, Environment, Anti-Corruption, Security, Social Responsibility).","link":"https:\/\/vittadello.net\/en\/categories-works-completed\/roads-tunnels-viaducts-and-railways\/","name":"Roads, tunnels, viaducts and railways","slug":"roads-tunnels-viaducts-and-railways","taxonomy":"portfolio_category","parent":53,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Roads, tunnels, viaducts and railways Archivi - Vittadello<\/title>\n<meta name=\"description\" content=\"Cutting-edge engineering skills and construction techniques for the construction of motorways, interchanges, tunnels, viaducts and other road works.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vittadello.net\/en\/categories-works-completed\/roads-tunnels-viaducts-and-railways\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roads, tunnels, viaducts and railways Archivi - Vittadello\" \/>\n<meta property=\"og:description\" content=\"Cutting-edge engineering skills and construction techniques for the construction of motorways, interchanges, tunnels, viaducts and other road works.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vittadello.net\/en\/categories-works-completed\/roads-tunnels-viaducts-and-railways\/\" \/>\n<meta property=\"og:site_name\" content=\"Vittadello\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/vittadello.net\\\/en\\\/categories-works-completed\\\/roads-tunnels-viaducts-and-railways\\\/\",\"url\":\"https:\\\/\\\/vittadello.net\\\/en\\\/categories-works-completed\\\/roads-tunnels-viaducts-and-railways\\\/\",\"name\":\"Roads, tunnels, viaducts and railways Archivi - Vittadello\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vittadello.net\\\/en\\\/#website\"},\"description\":\"Cutting-edge engineering skills and construction techniques for the construction of motorways, interchanges, tunnels, viaducts and other road works.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vittadello.net\\\/en\\\/categories-works-completed\\\/roads-tunnels-viaducts-and-railways\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vittadello.net\\\/en\\\/categories-works-completed\\\/roads-tunnels-viaducts-and-railways\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vittadello.net\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Infrastructure and transport\",\"item\":\"https:\\\/\\\/vittadello.net\\\/en\\\/categories-works-completed\\\/infrastructure-and-transport\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Roads, tunnels, viaducts and railways\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vittadello.net\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/vittadello.net\\\/en\\\/\",\"name\":\"Vittadello\",\"description\":\"Strade, Gallerie, Viadotti, Edilizia, Energie rinnovabili, discariche e impianti trattamento rifiuti, Bonifiche ambientali\",\"publisher\":{\"@id\":\"https:\\\/\\\/vittadello.net\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vittadello.net\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vittadello.net\\\/en\\\/#organization\",\"name\":\"Vittadello Spa\",\"url\":\"https:\\\/\\\/vittadello.net\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/vittadello.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vittadello.net\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Vittadello-Logo-500.png\",\"contentUrl\":\"https:\\\/\\\/vittadello.net\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Vittadello-Logo-500.png\",\"width\":500,\"height\":125,\"caption\":\"Vittadello Spa\"},\"image\":{\"@id\":\"https:\\\/\\\/vittadello.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/gruppovittadello\",\"https:\\\/\\\/www.instagram.com\\\/gruppovittadello\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/intercantieri-vittadello-spa\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Roads, tunnels, viaducts and railways Archivi - Vittadello","description":"Cutting-edge engineering skills and construction techniques for the construction of motorways, interchanges, tunnels, viaducts and other road works.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vittadello.net\/en\/categories-works-completed\/roads-tunnels-viaducts-and-railways\/","og_locale":"en_US","og_type":"article","og_title":"Roads, tunnels, viaducts and railways Archivi - Vittadello","og_description":"Cutting-edge engineering skills and construction techniques for the construction of motorways, interchanges, tunnels, viaducts and other road works.","og_url":"https:\/\/vittadello.net\/en\/categories-works-completed\/roads-tunnels-viaducts-and-railways\/","og_site_name":"Vittadello","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/vittadello.net\/en\/categories-works-completed\/roads-tunnels-viaducts-and-railways\/","url":"https:\/\/vittadello.net\/en\/categories-works-completed\/roads-tunnels-viaducts-and-railways\/","name":"Roads, tunnels, viaducts and railways Archivi - Vittadello","isPartOf":{"@id":"https:\/\/vittadello.net\/en\/#website"},"description":"Cutting-edge engineering skills and construction techniques for the construction of motorways, interchanges, tunnels, viaducts and other road works.","breadcrumb":{"@id":"https:\/\/vittadello.net\/en\/categories-works-completed\/roads-tunnels-viaducts-and-railways\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/vittadello.net\/en\/categories-works-completed\/roads-tunnels-viaducts-and-railways\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vittadello.net\/en\/"},{"@type":"ListItem","position":2,"name":"Infrastructure and transport","item":"https:\/\/vittadello.net\/en\/categories-works-completed\/infrastructure-and-transport\/"},{"@type":"ListItem","position":3,"name":"Roads, tunnels, viaducts and railways"}]},{"@type":"WebSite","@id":"https:\/\/vittadello.net\/en\/#website","url":"https:\/\/vittadello.net\/en\/","name":"Vittadello","description":"Strade, Gallerie, Viadotti, Edilizia, Energie rinnovabili, discariche e impianti trattamento rifiuti, Bonifiche ambientali","publisher":{"@id":"https:\/\/vittadello.net\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vittadello.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/vittadello.net\/en\/#organization","name":"Vittadello Spa","url":"https:\/\/vittadello.net\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/vittadello.net\/en\/#\/schema\/logo\/image\/","url":"https:\/\/vittadello.net\/wp-content\/uploads\/2023\/01\/Vittadello-Logo-500.png","contentUrl":"https:\/\/vittadello.net\/wp-content\/uploads\/2023\/01\/Vittadello-Logo-500.png","width":500,"height":125,"caption":"Vittadello Spa"},"image":{"@id":"https:\/\/vittadello.net\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/gruppovittadello","https:\/\/www.instagram.com\/gruppovittadello\/","https:\/\/www.linkedin.com\/company\/intercantieri-vittadello-spa"]}]}},"_links":{"self":[{"href":"https:\/\/vittadello.net\/en\/wp-json\/wp\/v2\/portfolio_category\/65","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vittadello.net\/en\/wp-json\/wp\/v2\/portfolio_category"}],"about":[{"href":"https:\/\/vittadello.net\/en\/wp-json\/wp\/v2\/taxonomies\/portfolio_category"}],"up":[{"embeddable":true,"href":"https:\/\/vittadello.net\/en\/wp-json\/wp\/v2\/portfolio_category\/53"}],"wp:post_type":[{"href":"https:\/\/vittadello.net\/en\/wp-json\/wp\/v2\/avada_portfolio?portfolio_category=65"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}